{"id":7775,"date":"2022-08-08T13:06:17","date_gmt":"2022-08-08T11:06:17","guid":{"rendered":"https:\/\/tcrplastics.eu\/equipo\/"},"modified":"2026-08-27T15:02:40","modified_gmt":"2026-08-27T13:02:40","slug":"equipo","status":"publish","type":"page","link":"https:\/\/tcrplastics.eu\/es\/equipo\/","title":{"rendered":"Equipo"},"content":{"rendered":"[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbtop\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb bg_image=\u00bb8735&#8243; bg_position=\u00bbcenter center\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb15%\u00bb bottom_padding=\u00bb20%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb shape_divider_height=\u00bb350&#8243; bg_image_animation=\u00bbfade-in\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbfast\u00bb shape_type=\u00bbmountains\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in\u00bb delay=\u00bb800&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb6%\u00bb bottom_padding=\u00bb6%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column_text]\n<h2><strong>Profesionales que hablan el idioma adecuado<\/strong><\/h2>\n[\/vc_column_text][vc_column_text css=\u00bb.vc_custom_1673948060483{padding-right: 10% !important;}\u00bb]Enfoque al cliente, profesionalismo, y experiencia en la industria: estas palabras caracterizan a nuestro equipo y nuestra forma de hacer negocios. Al combinar profesionales en diferentes \u00e1reas de especializaci\u00f3n, se crea un equipo muy fuerte. Bas\u00e1ndonos en nuestras experiencias individuales, nos esforzamos por ofrecer el mejor servicio personalizado para nuestros socios.[\/vc_column_text][tabbed_section style=\u00bbminimal\u00bb alignment=\u00bbcenter\u00bb spacing=\u00bbside-45px\u00bb tab_color=\u00bbextra-color-gradient-1&#8243; cta_button_style=\u00bbaccent-color\u00bb icon_size=\u00bb32&#8243;][tab icon_family=\u00bbnone\u00bb title=\u00bbEQUIPO\u00bb id=\u00bb1787835661363-3&#8243; tab_id=\u00bb1787835661363-7&#8243;][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6426&#8243; bio_image_url=\u00bb6318&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbGert Struijk\u00bb job_position=\u00bbCEO\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:g.struijk@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630101&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb7160&#8243; bio_image_url=\u00bb7160&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbRobert Struijk\u00bb job_position=\u00bbDirector Ejecutivo\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:r.struijk@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31653486716&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8609&#8243; bio_image_url=\u00bb8609&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbDavid Struijk\u00bb job_position=\u00bbDIRECTOR FINANCIERO\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:d.struijk@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630135&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8605&#8243; bio_image_url=\u00bb8605&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbVictor Libaudi\u00e8re\u00bb job_position=\u00bbCOO\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:libaudiere@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630108&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6444&#8243; bio_image_url=\u00bb6324&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbMatthias Zafri\u00bb job_position=\u00bbVentas &#8211; Alemania, Austria, Suiza\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:zafri@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+491629790207&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6446&#8243; bio_image_url=\u00bb6313&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbDavid Brun\u00bb job_position=\u00bbVentas &#8211; Francia\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:brun@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+33618362073&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8601&#8243; bio_image_url=\u00bb8601&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbThommy van Logtestijn\u00bb job_position=\u00bbVentas &#8211; Internacional\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:logtestijn@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630113&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb6451&#8243; bio_image_url=\u00bb6311&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbBoy Mannaerts\u00bb job_position=\u00bbVentas &#8211; Europa Central y Oriental\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:mannaerts@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630107&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6441&#8243; bio_image_url=\u00bb6314&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbErik Abrahamsen\u00bb job_position=\u00bbVentas &#8211; Benelux\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:abrahamsen@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630112&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8698&#8243; bio_image_url=\u00bb8692&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbTatiana Mironenko\u00bb job_position=\u00bbVentas &#8211; Europa Central y Oriental\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:tati.mironenko@gmail.com\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630176&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6479&#8243; bio_image_url=\u00bb6323&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbMario Huyghe\u00bb job_position=\u00bbVentas &#8211; Alemania, Austria, Suiza\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:m.huyghe@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+491608975381&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8423&#8243; bio_image_url=\u00bb8423&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbHans Nijhuis\u00bb job_position=\u00bbVentas &#8211; Pa\u00edses n\u00f3rdicos\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:nijhuis@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630109&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8514&#8243; bio_image_url=\u00bb8514&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbThijs Trumpi\u00bb job_position=\u00bbVentas &#8211; Pa\u00edses n\u00f3rdicos\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:trumpi@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630111&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8661&#8243; bio_image_url=\u00bb8661&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbAngelique Veugelers\u00bb job_position=\u00bbVentas &#8211; Benelux\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:Veugelers@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31618441495&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8676&#8243; bio_image_url=\u00bb8679&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbJustyna Rudniak\u00bb job_position=\u00bbVentas &#8211; Polonia\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:rudniak@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630176&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8682&#8243; bio_image_url=\u00bb8685&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbLukasz Rudniak\u00bb job_position=\u00bbVentas &#8211; Polonia\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:l.rudniak@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630176&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8695&#8243; bio_image_url=\u00bb8689&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbNiclas Huyghe\u00bb job_position=\u00bbVentas &#8211; Alemania, Austria, Suiza\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:n.huyghe@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630176&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8381&#8243; bio_image_url=\u00bb8381&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbRobert Verdiesen\u00bb job_position=\u00bbInstalaci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:verdiesen@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630176&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6459&#8243; bio_image_url=\u00bb6320&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbIngrid Hubers\u00bb job_position=\u00bbAdministraci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:hubers@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630132&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb7158&#8243; bio_image_url=\u00bb7158&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbSaskia Dikkeboom\u00bb job_position=\u00bbAdministraci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:dikkeboom@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630133&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6462&#8243; bio_image_url=\u00bb6322&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbMarcel Dielessen\u00bb job_position=\u00bbAdministraci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:dielessen@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630134&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8616&#8243; bio_image_url=\u00bb8616&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbSander Hoekstra\u00bb job_position=\u00bbAdministraci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:hoekstra@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630137&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6464&#8243; bio_image_url=\u00bb6328&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbRoy Bastiaansen\u00bb job_position=\u00bbContralor Financiero Asistente\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:bastiaansen@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630131&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb6485&#8243; bio_image_url=\u00bb6321&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbKoen van der Velden\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630129&#8243; social_link_1=\u00bbmailto:vandervelden@tcrplastics.eu\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6483&#8243; bio_image_url=\u00bb6325&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbOlena Kuijvenhoven\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:kuijvenhoven@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630124&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6473&#8243; bio_image_url=\u00bb6316&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbFloor Kempers\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:kempers@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630120&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6471&#8243; bio_image_url=\u00bb6327&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbRaymond Noordermeer\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:noordermeer@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630126&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb6466&#8243; bio_image_url=\u00bb6319&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbHenriette Speijer &#8211; van Baarle\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:speijer@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630136&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8375&#8243; bio_image_url=\u00bb8375&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbHenk Verschoor\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:verschoor@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630128&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6468&#8243; bio_image_url=\u00bb6330&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbSylvia Noyons\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:s.noyons@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630125&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb7156&#8243; bio_image_url=\u00bb7156&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbMaryse Lallement\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:lallement@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630121&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8372&#8243; bio_image_url=\u00bb8372&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbDawid Blanek\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:blanek@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630122&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8427&#8243; bio_image_url=\u00bb8427&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbMaciej Kashaniuk\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:kasjaniuk@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630127&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8644&#8243; bio_image_url=\u00bb8644&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbPaul Libaudi\u00e8re\u00bb job_position=\u00bbResponsable de REACH y Cumplimiento\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:p.libaudiere@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630138&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8669&#8243; bio_image_url=\u00bb8672&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbDaniela Libaudi\u00e8re\u00bb job_position=\u00bbCoordinador de marketing y comunicaci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:d.libaudiere@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630176&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8447&#8243; bio_image_url=\u00bb8447&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbFleur van de Kieft\u00bb job_position=\u00bbFideicomisario\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:mail@fleurvdkieft.nl\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31657388261&#8243;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=\u00bbnone\u00bb title=\u00bbVENTAS\u00bb id=\u00bb1787835661895-7&#8243; tab_id=\u00bb1787835661895-10&#8243;][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6426&#8243; bio_image_url=\u00bb6318&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbGert Struijk\u00bb job_position=\u00bbCEO\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:g.struijk@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630101&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb7160&#8243; bio_image_url=\u00bb7160&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbRobert Struijk\u00bb job_position=\u00bbDirecci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:r.struijk@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31653486716&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8605&#8243; bio_image_url=\u00bb8605&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbVictor Libaudi\u00e8re\u00bb job_position=\u00bbCOO\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:libaudiere@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630108&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb6446&#8243; bio_image_url=\u00bb6313&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbDavid Brun\u00bb job_position=\u00bbVentas &#8211; Francia\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:brun@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+33618362073&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8601&#8243; bio_image_url=\u00bb8601&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbThommy van Logtestijn\u00bb job_position=\u00bbVentas &#8211; Internacional\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:logtestijn@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630113&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6441&#8243; bio_image_url=\u00bb6314&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbErik Abrahamsen\u00bb job_position=\u00bbVentas &#8211; Benelux\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:abrahamsen@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630112&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8695&#8243; bio_image_url=\u00bb8689&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbNiclas Huyghe\u00bb job_position=\u00bbVentas &#8211; Alemania, Austria, Suiza\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:n.huyghe@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630176&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb6444&#8243; bio_image_url=\u00bb6324&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbMatthias Zafri\u00bb job_position=\u00bbVentas &#8211; Alemania, Austria, Suiza\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:zafri@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+491629790207&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6451&#8243; bio_image_url=\u00bb6311&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbBoy Mannaerts\u00bb job_position=\u00bbVentas &#8211; Europa Central y Oriental\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:mannaerts@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630107&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8698&#8243; bio_image_url=\u00bb8692&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbTatiana Mironenko\u00bb job_position=\u00bbVentas &#8211; Europa Central y Oriental\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:tati.mironenko@gmail.com\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630176&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6479&#8243; bio_image_url=\u00bb6323&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbMario Huyghe\u00bb job_position=\u00bbVentas &#8211; Alemania, Austria, Suiza\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:m.huyghe@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+491608975381&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8423&#8243; bio_image_url=\u00bb8423&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbHans Nijhuis\u00bb job_position=\u00bbVentas &#8211; Pa\u00edses n\u00f3rdicos\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:nijhuis@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630109&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8514&#8243; bio_image_url=\u00bb8514&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbThijs Trumpi\u00bb job_position=\u00bbVentas &#8211; Pa\u00edses n\u00f3rdicos\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:trumpi@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630111&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8661&#8243; bio_image_url=\u00bb8661&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbAngelique Veugelers\u00bb job_position=\u00bbVentas &#8211; Benelux\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:Veugelers@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31618441495&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8676&#8243; bio_image_url=\u00bb8679&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbJustyna Rudniak\u00bb job_position=\u00bbVentas &#8211; Polonia\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:rudniak@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630176&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8682&#8243; bio_image_url=\u00bb8685&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbLukasz Rudniak\u00bb job_position=\u00bbVentas &#8211; Polonia\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:l.rudniak@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bb+31767630176&#8243;][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=\u00bbnone\u00bb title=\u00bbFINANZAS\u00bb id=\u00bb1787835662031-7&#8243; tab_id=\u00bb1787835662031-3&#8243;][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8609&#8243; bio_image_url=\u00bb8609&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbDavid Struijk\u00bb job_position=\u00bbDIRECTOR FINANCIERO\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:d.struijk@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630135&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb6464&#8243; bio_image_url=\u00bb6328&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbRoy Bastiaansen\u00bb job_position=\u00bbContralor Financiero Asistente\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:bastiaansen@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630131&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb6462&#8243; bio_image_url=\u00bb6322&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbMarcel Dielessen\u00bb job_position=\u00bbAdministraci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:dielessen@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630134&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb6459&#8243; bio_image_url=\u00bb6320&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbIngrid Hubers\u00bb job_position=\u00bbAdministraci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:hubers@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630132&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb7158&#8243; bio_image_url=\u00bb7158&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbSaskia Dikkeboom\u00bb job_position=\u00bbAdministraci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:dikkeboom@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630133&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8616&#8243; bio_image_url=\u00bb8616&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbSander Hoekstra\u00bb job_position=\u00bbAdministraci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:hoekstra@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630137&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=\u00bbnone\u00bb title=\u00bbLOG\u00cdSTICA\u00bb id=\u00bb1787835662119-1&#8243; tab_id=\u00bb1787835662120-7&#8243;][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb6466&#8243; bio_image_url=\u00bb6319&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbHenriette Speijer &#8211; van Baarle\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:speijer@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630136&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8375&#8243; bio_image_url=\u00bb8375&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbHenk Verschoor\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:verschoor@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630128&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb6468&#8243; bio_image_url=\u00bb6330&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbSylvia Noyons\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:s.noyons@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630125&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb7156&#8243; bio_image_url=\u00bb7156&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbMaryse Lallement\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:lallement@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630121&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6485&#8243; bio_image_url=\u00bb6321&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbKoen van der Velden\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630129&#8243; social_link_1=\u00bbmailto:vandervelden@tcrplastics.eu\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6473&#8243; bio_image_url=\u00bb6316&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbFloor Kempers\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:kempers@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630120&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb6471&#8243; bio_image_url=\u00bb6327&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbRaymond Noordermeer\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:noordermeer@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630126&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb6483&#8243; bio_image_url=\u00bb6325&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbOlena Kuijvenhoven\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:kuijvenhoven@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630124&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8372&#8243; bio_image_url=\u00bb8372&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbDawid Blanek\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:blanek@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630122&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8427&#8243; bio_image_url=\u00bb8427&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbMaciej Kashaniuk\u00bb job_position=\u00bbLog\u00edstica\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:kasjaniuk@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630127&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][team_member image_url=\u00bb8644&#8243; bio_image_url=\u00bb8644&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbPaul Libaudi\u00e8re\u00bb job_position=\u00bbResponsable de REACH y Cumplimiento\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:p.libaudiere@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630138&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=\u00bbnone\u00bb title=\u00bbADMINISTRACI\u00d3N\u00bb id=\u00bb1787835662224-1&#8243; tab_id=\u00bb1787835662224-2&#8243;][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8381&#8243; bio_image_url=\u00bb8381&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbRobert Verdiesen\u00bb job_position=\u00bbInstalaci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:verdiesen@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630176&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][\/vc_column_inner][\/vc_row_inner][\/tab][tab icon_family=\u00bbnone\u00bb title=\u00bbMARKETING\u00bb id=\u00bb1787835662290-4&#8243; tab_id=\u00bb1787835662290-8&#8243;][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][team_member image_url=\u00bb8669&#8243; bio_image_url=\u00bb8672&#8243; team_memeber_style=\u00bbbio_fullscreen\u00bb image_loading=\u00bbdefault\u00bb name=\u00bbDaniela Libaudi\u00e8re\u00bb job_position=\u00bbCoordinador de marketing y comunicaci\u00f3n\u00bb social_icon_1=\u00bbfa fa-envelope-square\u00bb social_link_1=\u00bbmailto:d.libaudiere@tcrplastics.eu\u00bb social_icon_2=\u00bbfa fa-phone-square\u00bb social_link_2=\u00bbtel:+31767630176&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbgrow-in\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb bg_image_animation=\u00bbnone\u00bb][\/vc_column_inner][\/vc_row_inner][\/tab][\/tabbed_section][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbtop\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb bg_image=\u00bb8735&#8243; bg_position=\u00bbcenter center\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb15%\u00bb bottom_padding=\u00bb20%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb shape_divider_height=\u00bb350&#8243;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-7775","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Profesionales que hablan tu idioma<\/title>\n<meta name=\"description\" content=\"Desde nuestras \u00e1reas individuales de especializaci\u00f3n y experiencia, ofrecemos siempre a nuestros clientes los mejores servicios, adaptados a sus deseos y necesidades.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tcrplastics.eu\/es\/equipo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profesionales que hablan tu idioma\" \/>\n<meta property=\"og:description\" content=\"Desde nuestras \u00e1reas individuales de especializaci\u00f3n y experiencia, ofrecemos siempre a nuestros clientes los mejores servicios, adaptados a sus deseos y necesidades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tcrplastics.eu\/es\/equipo\/\" \/>\n<meta property=\"og:site_name\" content=\"TCR Plastics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-27T13:02:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/equipo\\\/\",\"url\":\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/equipo\\\/\",\"name\":\"Profesionales que hablan tu idioma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/#website\"},\"datePublished\":\"2022-08-08T11:06:17+00:00\",\"dateModified\":\"2026-08-27T13:02:40+00:00\",\"description\":\"Desde nuestras \u00e1reas individuales de especializaci\u00f3n y experiencia, ofrecemos siempre a nuestros clientes los mejores servicios, adaptados a sus deseos y necesidades.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/equipo\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/\",\"name\":\"TCR Plastics\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/#organization\",\"name\":\"TCR plastics\",\"url\":\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tcrplastics.eu\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/header.png\",\"contentUrl\":\"https:\\\/\\\/tcrplastics.eu\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/header.png\",\"width\":747,\"height\":405,\"caption\":\"TCR plastics\"},\"image\":{\"@id\":\"https:\\\/\\\/tcrplastics.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Profesionales que hablan tu idioma","description":"Desde nuestras \u00e1reas individuales de especializaci\u00f3n y experiencia, ofrecemos siempre a nuestros clientes los mejores servicios, adaptados a sus deseos y necesidades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tcrplastics.eu\/es\/equipo\/","og_locale":"es_ES","og_type":"article","og_title":"Profesionales que hablan tu idioma","og_description":"Desde nuestras \u00e1reas individuales de especializaci\u00f3n y experiencia, ofrecemos siempre a nuestros clientes los mejores servicios, adaptados a sus deseos y necesidades.","og_url":"https:\/\/tcrplastics.eu\/es\/equipo\/","og_site_name":"TCR Plastics","article_modified_time":"2026-08-27T13:02:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tcrplastics.eu\/es\/equipo\/","url":"https:\/\/tcrplastics.eu\/es\/equipo\/","name":"Profesionales que hablan tu idioma","isPartOf":{"@id":"https:\/\/tcrplastics.eu\/es\/#website"},"datePublished":"2022-08-08T11:06:17+00:00","dateModified":"2026-08-27T13:02:40+00:00","description":"Desde nuestras \u00e1reas individuales de especializaci\u00f3n y experiencia, ofrecemos siempre a nuestros clientes los mejores servicios, adaptados a sus deseos y necesidades.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tcrplastics.eu\/es\/equipo\/"]}]},{"@type":"WebSite","@id":"https:\/\/tcrplastics.eu\/es\/#website","url":"https:\/\/tcrplastics.eu\/es\/","name":"TCR Plastics","description":"","publisher":{"@id":"https:\/\/tcrplastics.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tcrplastics.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tcrplastics.eu\/es\/#organization","name":"TCR plastics","url":"https:\/\/tcrplastics.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tcrplastics.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/tcrplastics.eu\/wp-content\/uploads\/2022\/08\/header.png","contentUrl":"https:\/\/tcrplastics.eu\/wp-content\/uploads\/2022\/08\/header.png","width":747,"height":405,"caption":"TCR plastics"},"image":{"@id":"https:\/\/tcrplastics.eu\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tcrplastics.eu\/es\/wp-json\/wp\/v2\/pages\/7775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tcrplastics.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tcrplastics.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tcrplastics.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tcrplastics.eu\/es\/wp-json\/wp\/v2\/comments?post=7775"}],"version-history":[{"count":2,"href":"https:\/\/tcrplastics.eu\/es\/wp-json\/wp\/v2\/pages\/7775\/revisions"}],"predecessor-version":[{"id":8961,"href":"https:\/\/tcrplastics.eu\/es\/wp-json\/wp\/v2\/pages\/7775\/revisions\/8961"}],"wp:attachment":[{"href":"https:\/\/tcrplastics.eu\/es\/wp-json\/wp\/v2\/media?parent=7775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}